{"id":28021,"date":"2025-12-11T14:15:21","date_gmt":"2025-12-11T07:15:21","guid":{"rendered":"https:\/\/www.rn.ac.th\/default\/?p=28021"},"modified":"2025-12-11T14:15:21","modified_gmt":"2025-12-11T07:15:21","slug":"%e0%b8%82%e0%b8%ad%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a2%e0%b8%b4%e0%b8%99%e0%b8%94%e0%b8%b5%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%99%e0%b8%b1%e0%b8%81-568","status":"publish","type":"post","link":"https:\/\/www.rn.ac.th\/default\/archives\/28021","title":{"rendered":"\u0e02\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e23\u0e2d\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e15\u0e49\u0e19 KU-EDs Cover Dance Contest 2025 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 5 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32"},"content":{"rendered":"<p>\u0e02\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e0d\u0e34\u0e07\u0e08\u0e38\u0e11\u0e32\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c \u0e1e\u0e27\u0e07\u0e17\u0e2d\u0e07 \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 2\/4 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e23\u0e38\u0e15\u0e22\u0e32 \u0e08\u0e4d\u0e32\u0e1b\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 4\/8 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e31\u0e0a\u0e23\u0e1e\u0e23 \u0e40\u0e1e\u0e0a\u0e23\u0e41\u0e2d\u0e19 \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 4\/14 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e02\u0e27\u0e31\u0e0d\u0e28\u0e34\u0e23\u0e34 \u0e25\u0e34\u0e02\u0e34\u0e15\u0e18\u0e19\u0e32\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 5\/2 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e01\u0e31\u0e0d\u0e0d\u0e32\u0e20\u0e31\u0e04 \u0e08\u0e23\u0e31\u0e2a\u0e27\u0e34\u0e01\u0e23\u0e31\u0e22\u0e01\u0e38\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 5\/8 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e13\u0e31\u0e10\u0e0a\u0e32\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e04\u0e39\u0e28\u0e23\u0e35\u0e40\u0e17\u0e1e\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 5\/14 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e23\u0e2d\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 1,000 \u0e1a\u0e32\u0e17 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e15\u0e49\u0e19 KU-EDs Cover Dance Contest 2025 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 5 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e42\u0e14\u0e22\u0e04\u0e13\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e4d\u0e32\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e42\u0e14\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e18\u0e34\u0e14\u0e32 \u0e19\u0e34\u0e1e\u0e34\u0e10\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e23\u0e18\u0e34\u0e21\u0e32 \u0e40\u0e2d\u0e01\u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e13\u0e20\u0e31\u0e2a\u0e2a\u0e23\u0e4c \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e30\u0e2a\u0e38\u0e15<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-28022 aligncenter\" src=\"https:\/\/www.rn.ac.th\/default\/wp-content\/uploads\/2025\/12\/C-dance68.png\" alt=\"\" width=\"862\" height=\"540\" srcset=\"https:\/\/www.rn.ac.th\/default\/wp-content\/uploads\/2025\/12\/C-dance68.png 862w, https:\/\/www.rn.ac.th\/default\/wp-content\/uploads\/2025\/12\/C-dance68-300x188.png 300w, https:\/\/www.rn.ac.th\/default\/wp-content\/uploads\/2025\/12\/C-dance68-768x481.png 768w\" sizes=\"(max-width: 862px) 100vw, 862px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e02\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e0d\u0e34\u0e07\u0e08\u0e38\u0e11\u0e32\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c \u0e1e\u0e27\u0e07\u0e17\u0e2d\u0e07 \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36&#8230;<\/p>\n","protected":false},"author":8,"featured_media":28023,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[1,40],"tags":[],"_links":{"self":[{"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/posts\/28021"}],"collection":[{"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/comments?post=28021"}],"version-history":[{"count":1,"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/posts\/28021\/revisions"}],"predecessor-version":[{"id":28024,"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/posts\/28021\/revisions\/28024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/media\/28023"}],"wp:attachment":[{"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/media?parent=28021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/categories?post=28021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rn.ac.th\/default\/wp-json\/wp\/v2\/tags?post=28021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}